{"id":319,"count":10,"description":"","link":"https:\/\/phanimenal.de\/index.php\/tag\/ace\/","name":"Ace","slug":"ace","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.2.1 (Yoast SEO v20.2.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ace Archive - Phanimenal - T\u00e4glich interessante Anime News und Gaming News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phanimenal.de\/index.php\/tag\/ace\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ace Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phanimenal.de\/index.php\/tag\/ace\/\" \/>\n<meta property=\"og:site_name\" content=\"Phanimenal - T\u00e4glich interessante Anime News und Gaming News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/phanimenal.de\/index.php\/tag\/ace\/\",\"url\":\"https:\/\/phanimenal.de\/index.php\/tag\/ace\/\",\"name\":\"Ace Archive - Phanimenal - T\u00e4glich interessante Anime News und Gaming News\",\"isPartOf\":{\"@id\":\"https:\/\/phanimenal.de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/phanimenal.de\/index.php\/tag\/ace\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/phanimenal.de\/index.php\/tag\/ace\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/phanimenal.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/phanimenal.de\/#website\",\"url\":\"https:\/\/phanimenal.de\/\",\"name\":\"Phanimenal - T\u00e4glich interessante Anime News und Gaming News\",\"description\":\"Auf Phanimenal findest du die aktuellsten Anime-News aus Japan und Deutschland\",\"publisher\":{\"@id\":\"https:\/\/phanimenal.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/phanimenal.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/phanimenal.de\/#organization\",\"name\":\"Phanimenal\",\"url\":\"https:\/\/phanimenal.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/phanimenal.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/phanimenal.de\/wp-content\/uploads\/\/2016\/04\/logo.png\",\"contentUrl\":\"https:\/\/phanimenal.de\/wp-content\/uploads\/\/2016\/04\/logo.png\",\"width\":170,\"height\":70,\"caption\":\"Phanimenal\"},\"image\":{\"@id\":\"https:\/\/phanimenal.de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/phanimenal\",\"https:\/\/www.instagram.com\/phanimenal\",\"https:\/\/www.youtube.com\/channel\/UCbK_Z9H_JoD0sWZeb2guVxw\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ace Archive - Phanimenal - T\u00e4glich interessante Anime News und Gaming News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phanimenal.de\/index.php\/tag\/ace\/","og_locale":"de_DE","og_type":"article","og_title":"Ace Archive","og_url":"https:\/\/phanimenal.de\/index.php\/tag\/ace\/","og_site_name":"Phanimenal - T\u00e4glich interessante Anime News und Gaming News","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/phanimenal.de\/index.php\/tag\/ace\/","url":"https:\/\/phanimenal.de\/index.php\/tag\/ace\/","name":"Ace Archive - Phanimenal - T\u00e4glich interessante Anime News und Gaming News","isPartOf":{"@id":"https:\/\/phanimenal.de\/#website"},"breadcrumb":{"@id":"https:\/\/phanimenal.de\/index.php\/tag\/ace\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/phanimenal.de\/index.php\/tag\/ace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/phanimenal.de\/"},{"@type":"ListItem","position":2,"name":"Ace"}]},{"@type":"WebSite","@id":"https:\/\/phanimenal.de\/#website","url":"https:\/\/phanimenal.de\/","name":"Phanimenal - T\u00e4glich interessante Anime News und Gaming News","description":"Auf Phanimenal findest du die aktuellsten Anime-News aus Japan und Deutschland","publisher":{"@id":"https:\/\/phanimenal.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phanimenal.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/phanimenal.de\/#organization","name":"Phanimenal","url":"https:\/\/phanimenal.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/phanimenal.de\/#\/schema\/logo\/image\/","url":"https:\/\/phanimenal.de\/wp-content\/uploads\/\/2016\/04\/logo.png","contentUrl":"https:\/\/phanimenal.de\/wp-content\/uploads\/\/2016\/04\/logo.png","width":170,"height":70,"caption":"Phanimenal"},"image":{"@id":"https:\/\/phanimenal.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/phanimenal","https:\/\/www.instagram.com\/phanimenal","https:\/\/www.youtube.com\/channel\/UCbK_Z9H_JoD0sWZeb2guVxw"]}]}},"_links":{"self":[{"href":"https:\/\/phanimenal.de\/index.php\/wp-json\/wp\/v2\/tags\/319"}],"collection":[{"href":"https:\/\/phanimenal.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/phanimenal.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/phanimenal.de\/index.php\/wp-json\/wp\/v2\/posts?tags=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}